{"id":13411,"date":"2025-11-11T17:00:26","date_gmt":"2025-11-11T17:00:26","guid":{"rendered":"https:\/\/acimga.it\/?p=13411"},"modified":"2025-11-11T17:12:55","modified_gmt":"2025-11-11T17:12:55","slug":"federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero","status":"publish","type":"post","link":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/","title":{"rendered":"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#8217;ESTERO"},"content":{"rendered":"<p>FEDERMACCHINE, in collaborazione con lo Studio Arletti &amp;Partners ha organizzato un incontro di <strong>aggiornamento online dedicato alle novit\u00e0 in tema di impiego di personale all\u2019estero e regole di impiego di personale extra comunitario.<\/strong><\/p>\n<p>L\u2019evento si svolger\u00e0 online <strong>venerd\u00ec 28 novembre dalle 10:00 alle 12:00.\u00a0\u00a0<\/strong><\/p>\n<p>Il webinar si dedicher\u00e0 nello specifico a:<\/p>\n<ul>\n<li>ES &#8211; controllo delle frontiere esterne di Schengen cosa comporta per le aziende italiane e conseguenze della violazione delle norme;<\/li>\n<li>Visto Tecnico per il Brasile, cambio normativo: le nuove modalit\u00e0 per entrare nel paese per installazioni e manutenzioni;<\/li>\n<li>Nuovo Decreto Flussi: aperta la finestra per assunzioni di lavoratori extra comunitari non qualificati: modalit\u00e0 con cui le aziende potranno usufruirne;<\/li>\n<li>I nuovi controlli alla frontiera negli Stati Uniti: l\u2019amministrazione Trump ha introdotto misure pi\u00f9 restrittive di controlli all\u2019ingresso nel Paese. Si esporranno pertanto informazioni utili sulla prevenzione e la gestione delle verifiche degli ufficiali di frontiera;<\/li>\n<li>Stabile Organizzazione da Service: una barriera sempre pi\u00f9 diffusa ad operare all\u2019estero per la manutenzione delle macchine con personale italiano;<\/li>\n<li>Ritenute fiscali all\u2019estero sulle nostre fatture di service: come evitarle, i casi in cui possono divenire un definitivo minore incasso, come recuperarle integralmente;<\/li>\n<li>Nuovo Accordo di sicurezza sociale con l\u2019Albania: quali vantaggi per le aziende italiane nel distacco di proprio personale in Albania e viceversa;<\/li>\n<li>Polizze Assicurative personale dipendente in servizio all\u2019estero: nuovi chiarimenti in merito al loro trattamento fiscale dall\u2019Agenzia delle Entrate con Interpello 249\/25;<\/li>\n<li>Novit\u00e0 in tema di Distacco per interventi tecnici in Unione Europea: elenco delle ultime novit\u00e0 normative introdotte di recente dai singoli stati europei;<\/li>\n<li>Condividere i dati delle trasferte estere in azienda per rispettare le norme: dimostrazione del software web Atlasposting come modello di processo aziendale per effettuare le trasferte estere in regola con le norme italiane ed estere.<\/li>\n<\/ul>\n<a href='https:\/\/us06web.zoom.us\/meeting\/register\/kaQRhZPhRaiBVVTxiqiggw#\/registration' class='big-button bigblack' target=\"_blank\">Partecipa al webinar<\/a>\n","protected":false},"excerpt":{"rendered":"<p>FEDERMACCHINE, in collaborazione con lo Studio Arletti &amp;Partners ha organizzato un incontro di aggiornamento online dedicato alle novit\u00e0 in tema di impiego di personale all\u2019estero e regole di impiego di personale extra comunitario. L\u2019evento si svolger\u00e0 online venerd\u00ec 28 novembre dalle 10:00 alle 12:00.\u00a0\u00a0 Il webinar si dedicher\u00e0 nello specifico a: ES &#8211; controllo delle [&hellip;]<\/p>\n","protected":false},"author":586,"featured_media":13412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,20],"tags":[],"class_list":["post-13411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-norme-tecniche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#039;ESTERO - Acimga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#039;ESTERO - Acimga\" \/>\n<meta property=\"og:description\" content=\"FEDERMACCHINE, in collaborazione con lo Studio Arletti &amp;Partners ha organizzato un incontro di aggiornamento online dedicato alle novit\u00e0 in tema di impiego di personale all\u2019estero e regole di impiego di personale extra comunitario. L\u2019evento si svolger\u00e0 online venerd\u00ec 28 novembre dalle 10:00 alle 12:00.\u00a0\u00a0 Il webinar si dedicher\u00e0 nello specifico a: ES &#8211; controllo delle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/\" \/>\n<meta property=\"og:site_name\" content=\"Acimga\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T17:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T17:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acimga.it\/wp-content\/uploads\/2025\/11\/trasferte-nl-part.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gwyn Garrett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Acimga1947\" \/>\n<meta name=\"twitter:site\" content=\"@Acimga1947\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gwyn Garrett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/\"},\"author\":{\"name\":\"Gwyn Garrett\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#\\\/schema\\\/person\\\/e7d66db085dfe21491c14f371f7f8a9a\"},\"headline\":\"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#8217;ESTERO\",\"datePublished\":\"2025-11-11T17:00:26+00:00\",\"dateModified\":\"2025-11-11T17:12:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/\"},\"wordCount\":327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acimga.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/trasferte-nl-part.png\",\"articleSection\":[\"Comunicazione\",\"Norme Tecniche\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/\",\"url\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/\",\"name\":\"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL'ESTERO - Acimga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acimga.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/trasferte-nl-part.png\",\"datePublished\":\"2025-11-11T17:00:26+00:00\",\"dateModified\":\"2025-11-11T17:12:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acimga.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/trasferte-nl-part.png\",\"contentUrl\":\"https:\\\/\\\/acimga.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/trasferte-nl-part.png\",\"width\":800,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acimga.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#8217;ESTERO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/acimga.it\\\/it\\\/\",\"name\":\"Acimga\",\"description\":\"Costruttori Italiani di Macchine per l\u2019Industria Grafica, Cartotecnica, Cartaria, di Trasformazione e Affini\",\"publisher\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acimga.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#organization\",\"name\":\"ACIMGA\",\"url\":\"https:\\\/\\\/acimga.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/acimga.it\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo-payoff.svg\",\"contentUrl\":\"https:\\\/\\\/acimga.it\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo-payoff.svg\",\"width\":288,\"height\":80,\"caption\":\"ACIMGA\"},\"image\":{\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Acimga1947\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/acimga?trk=nmp_rec_act_company_photo\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqzHaOsul8rWTGHSrvq3FUw\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acimga.it\\\/it\\\/#\\\/schema\\\/person\\\/e7d66db085dfe21491c14f371f7f8a9a\",\"name\":\"Gwyn Garrett\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3aef2eca19bf1643ebeb9a8c157d0f87d1f35cd02b69794dd6130fe56ee6afd0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3aef2eca19bf1643ebeb9a8c157d0f87d1f35cd02b69794dd6130fe56ee6afd0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3aef2eca19bf1643ebeb9a8c157d0f87d1f35cd02b69794dd6130fe56ee6afd0?s=96&d=mm&r=g\",\"caption\":\"Gwyn Garrett\"},\"url\":\"https:\\\/\\\/acimga.it\\\/it\\\/author\\\/gwynedd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL'ESTERO - Acimga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/","og_locale":"it_IT","og_type":"article","og_title":"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL'ESTERO - Acimga","og_description":"FEDERMACCHINE, in collaborazione con lo Studio Arletti &amp;Partners ha organizzato un incontro di aggiornamento online dedicato alle novit\u00e0 in tema di impiego di personale all\u2019estero e regole di impiego di personale extra comunitario. L\u2019evento si svolger\u00e0 online venerd\u00ec 28 novembre dalle 10:00 alle 12:00.\u00a0\u00a0 Il webinar si dedicher\u00e0 nello specifico a: ES &#8211; controllo delle [&hellip;]","og_url":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/","og_site_name":"Acimga","article_published_time":"2025-11-11T17:00:26+00:00","article_modified_time":"2025-11-11T17:12:55+00:00","og_image":[{"width":800,"height":650,"url":"https:\/\/acimga.it\/wp-content\/uploads\/2025\/11\/trasferte-nl-part.png","type":"image\/png"}],"author":"Gwyn Garrett","twitter_card":"summary_large_image","twitter_creator":"@Acimga1947","twitter_site":"@Acimga1947","twitter_misc":{"Scritto da":"Gwyn Garrett","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#article","isPartOf":{"@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/"},"author":{"name":"Gwyn Garrett","@id":"https:\/\/acimga.it\/it\/#\/schema\/person\/e7d66db085dfe21491c14f371f7f8a9a"},"headline":"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#8217;ESTERO","datePublished":"2025-11-11T17:00:26+00:00","dateModified":"2025-11-11T17:12:55+00:00","mainEntityOfPage":{"@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/"},"wordCount":327,"commentCount":0,"publisher":{"@id":"https:\/\/acimga.it\/it\/#organization"},"image":{"@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/acimga.it\/wp-content\/uploads\/2025\/11\/trasferte-nl-part.png","articleSection":["Comunicazione","Norme Tecniche"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/","url":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/","name":"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL'ESTERO - Acimga","isPartOf":{"@id":"https:\/\/acimga.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#primaryimage"},"image":{"@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/acimga.it\/wp-content\/uploads\/2025\/11\/trasferte-nl-part.png","datePublished":"2025-11-11T17:00:26+00:00","dateModified":"2025-11-11T17:12:55+00:00","breadcrumb":{"@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#primaryimage","url":"https:\/\/acimga.it\/wp-content\/uploads\/2025\/11\/trasferte-nl-part.png","contentUrl":"https:\/\/acimga.it\/wp-content\/uploads\/2025\/11\/trasferte-nl-part.png","width":800,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/acimga.it\/it\/federmacchine-webinar-di-aggiornamento-sulle-trasferte-del-personale-allestero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acimga.it\/it\/"},{"@type":"ListItem","position":2,"name":"FEDERMACCHINE: WEBINAR DI AGGIORNAMENTO SULLE TRASFERTE DEL PERSONALE ALL&#8217;ESTERO"}]},{"@type":"WebSite","@id":"https:\/\/acimga.it\/it\/#website","url":"https:\/\/acimga.it\/it\/","name":"Acimga","description":"Costruttori Italiani di Macchine per l\u2019Industria Grafica, Cartotecnica, Cartaria, di Trasformazione e Affini","publisher":{"@id":"https:\/\/acimga.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acimga.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/acimga.it\/it\/#organization","name":"ACIMGA","url":"https:\/\/acimga.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acimga.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/acimga.it\/wp-content\/uploads\/2020\/11\/logo-payoff.svg","contentUrl":"https:\/\/acimga.it\/wp-content\/uploads\/2020\/11\/logo-payoff.svg","width":288,"height":80,"caption":"ACIMGA"},"image":{"@id":"https:\/\/acimga.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Acimga1947","https:\/\/www.linkedin.com\/company\/acimga?trk=nmp_rec_act_company_photo","https:\/\/www.youtube.com\/channel\/UCqzHaOsul8rWTGHSrvq3FUw\/videos"]},{"@type":"Person","@id":"https:\/\/acimga.it\/it\/#\/schema\/person\/e7d66db085dfe21491c14f371f7f8a9a","name":"Gwyn Garrett","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3aef2eca19bf1643ebeb9a8c157d0f87d1f35cd02b69794dd6130fe56ee6afd0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3aef2eca19bf1643ebeb9a8c157d0f87d1f35cd02b69794dd6130fe56ee6afd0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3aef2eca19bf1643ebeb9a8c157d0f87d1f35cd02b69794dd6130fe56ee6afd0?s=96&d=mm&r=g","caption":"Gwyn Garrett"},"url":"https:\/\/acimga.it\/it\/author\/gwynedd\/"}]}},"_links":{"self":[{"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/posts\/13411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/users\/586"}],"replies":[{"embeddable":true,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/comments?post=13411"}],"version-history":[{"count":3,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/posts\/13411\/revisions"}],"predecessor-version":[{"id":13427,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/posts\/13411\/revisions\/13427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/media\/13412"}],"wp:attachment":[{"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/media?parent=13411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/categories?post=13411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acimga.it\/it\/wp-json\/wp\/v2\/tags?post=13411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}